{"id":2584,"date":"2025-11-13T13:15:15","date_gmt":"2025-11-13T12:15:15","guid":{"rendered":"https:\/\/bartelt.io\/?post_type=jobs&#038;p=2584"},"modified":"2025-11-13T13:49:21","modified_gmt":"2025-11-13T12:49:21","slug":"java-software-entwicklerin","status":"publish","type":"jobs","link":"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/","title":{"rendered":"Java-Software-Entwickler:in (m\/w\/d) f\u00fcr unser Laborinformationssystem datalabX"},"featured_media":0,"template":"","class_list":["post-2584","jobs","type-jobs","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Java-Software-Entwickler:in (m\/w\/d) f\u00fcr unser Laborinformationssystem datalabX - bartelt.io<\/title>\n<meta name=\"description\" content=\"Gehe deinen Weg mit uns - Wir bei Bartelt freuen uns sehr auf dich, um uns gemeinsam weiterentwickeln zu k\u00f6nnen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Java-Software-Entwickler:in (m\/w\/d) f\u00fcr unser Laborinformationssystem datalabX - bartelt.io\" \/>\n<meta property=\"og:description\" content=\"Gehe deinen Weg mit uns - Wir bei Bartelt freuen uns sehr auf dich, um uns gemeinsam weiterentwickeln zu k\u00f6nnen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/\" \/>\n<meta property=\"og:site_name\" content=\"bartelt.io\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T12:49:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bartelt.io\\\/en\\\/jobs\\\/java-software-entwicklerin\\\/\",\"url\":\"https:\\\/\\\/bartelt.io\\\/en\\\/jobs\\\/java-software-entwicklerin\\\/\",\"name\":\"Java-Software-Entwickler:in (m\\\/w\\\/d) f\u00fcr unser Laborinformationssystem datalabX - bartelt.io\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bartelt.io\\\/en\\\/#website\"},\"datePublished\":\"2025-11-13T12:15:15+00:00\",\"dateModified\":\"2025-11-13T12:49:21+00:00\",\"description\":\"Gehe deinen Weg mit uns - Wir bei Bartelt freuen uns sehr auf dich, um uns gemeinsam weiterentwickeln zu k\u00f6nnen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bartelt.io\\\/en\\\/jobs\\\/java-software-entwicklerin\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bartelt.io\\\/en\\\/jobs\\\/java-software-entwicklerin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bartelt.io\\\/en\\\/jobs\\\/java-software-entwicklerin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bartelt.io\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Java-Software-Entwickler:in (m\\\/w\\\/d) f\u00fcr unser Laborinformationssystem datalabX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bartelt.io\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bartelt.io\\\/en\\\/\",\"name\":\"bartelt.io\",\"description\":\"Softwarel\u00f6sungen f\u00fcr Ihr Labor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bartelt.io\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Java-Software-Entwickler:in (m\/w\/d) f\u00fcr unser Laborinformationssystem datalabX - bartelt.io","description":"Gehe deinen Weg mit uns - Wir bei Bartelt freuen uns sehr auf dich, um uns gemeinsam weiterentwickeln zu k\u00f6nnen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/","og_locale":"en_US","og_type":"article","og_title":"Java-Software-Entwickler:in (m\/w\/d) f\u00fcr unser Laborinformationssystem datalabX - bartelt.io","og_description":"Gehe deinen Weg mit uns - Wir bei Bartelt freuen uns sehr auf dich, um uns gemeinsam weiterentwickeln zu k\u00f6nnen!","og_url":"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/","og_site_name":"bartelt.io","article_modified_time":"2025-11-13T12:49:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/","url":"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/","name":"Java-Software-Entwickler:in (m\/w\/d) f\u00fcr unser Laborinformationssystem datalabX - bartelt.io","isPartOf":{"@id":"https:\/\/bartelt.io\/en\/#website"},"datePublished":"2025-11-13T12:15:15+00:00","dateModified":"2025-11-13T12:49:21+00:00","description":"Gehe deinen Weg mit uns - Wir bei Bartelt freuen uns sehr auf dich, um uns gemeinsam weiterentwickeln zu k\u00f6nnen!","breadcrumb":{"@id":"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bartelt.io\/en\/jobs\/java-software-entwicklerin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bartelt.io\/en\/"},{"@type":"ListItem","position":2,"name":"Java-Software-Entwickler:in (m\/w\/d) f\u00fcr unser Laborinformationssystem datalabX"}]},{"@type":"WebSite","@id":"https:\/\/bartelt.io\/en\/#website","url":"https:\/\/bartelt.io\/en\/","name":"bartelt.io","description":"Softwarel\u00f6sungen f\u00fcr Ihr Labor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bartelt.io\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bartelt.io\/en\/wp-json\/wp\/v2\/jobs\/2584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bartelt.io\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/bartelt.io\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/bartelt.io\/en\/wp-json\/wp\/v2\/media?parent=2584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}